{"id":9670,"date":"2025-11-07T18:01:34","date_gmt":"2025-11-07T18:01:34","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=9670"},"modified":"2025-11-07T18:01:34","modified_gmt":"2025-11-07T18:01:34","slug":"desafortunadas-las-declaraciones-del-padre-pistolas-lorena-alfaro","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/11\/07\/desafortunadas-las-declaraciones-del-padre-pistolas-lorena-alfaro\/","title":{"rendered":"Desafortunadas las declaraciones del Padre Pistolas: Lorena Alfaro"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>La presidenta de Irapuato, Lorena Alfaro Garc\u00eda, se pronunci\u00f3 sobre las amenazas del sacerdote Alfredo Gallegos Lara, conocido como \u201cPadre Pistolas\u201d, contra la gobernadora Libia Dennise Garc\u00eda Mu\u00f1oz Ledo, calificando el mensaje como desafortunado.<\/strong><\/p>\n\n\n\n<p><strong>El hecho&nbsp;&nbsp;surge en el marco del proyecto del acueducto de la Presa Sol\u00eds, obra que busca garantizar agua a municipios que enfrentan escasez, sin afectar los intereses de productores ni de otras localidades.<\/strong><\/p>\n\n\n\n<p><strong>Alfaro Garc\u00eda enfatiz\u00f3 que este tipo de mensajes no contribuyen a la construcci\u00f3n de acuerdos ni al di\u00e1logo, y que la ciudadan\u00eda requiere tranquilidad y seguridad frente a proyectos estrat\u00e9gicos de infraestructura.<\/strong><\/p>\n\n\n\n<p><strong>El acueducto ha generado debate entre municipios y sectores productivos, quienes buscan asegurar que la obra no comprometa sus recursos h\u00eddricos.<\/strong><\/p>\n\n\n\n<p><strong>La presidenta municipal destac\u00f3 la necesidad de fomentar un ambiente de paz, equidad y concordia, priorizando el di\u00e1logo sobre la confrontaci\u00f3n.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de Irapuato, Lorena Alfaro Garc\u00eda, se pronunci\u00f3 sobre las amenazas del sacerdote Alfredo Gallegos Lara, conocido como \u201cPadre Pistolas\u201d, contra la gobernadora Libia Dennise Garc\u00eda Mu\u00f1oz Ledo, calificando el mensaje como desafortunado. El hecho&nbsp;&nbsp;surge en el marco del proyecto del acueducto de la Presa Sol\u00eds, obra que busca garantizar agua a municipios que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9630,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-irapuato"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/9670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=9670"}],"version-history":[{"count":1,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/9670\/revisions"}],"predecessor-version":[{"id":9671,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/9670\/revisions\/9671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media\/9630"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=9670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=9670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=9670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}