{"id":8923,"date":"2025-10-07T20:38:25","date_gmt":"2025-10-07T20:38:25","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=8923"},"modified":"2025-10-07T20:38:25","modified_gmt":"2025-10-07T20:38:25","slug":"hombre-es-atacado-a-balazos-mientras-transmitia-en-vivo-en-salvarierra","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/10\/07\/hombre-es-atacado-a-balazos-mientras-transmitia-en-vivo-en-salvarierra\/","title":{"rendered":"Hombre es atacado a balazos mientras transmit\u00eda en vivo en Salvarierra"},"content":{"rendered":"\n<p><strong>Un comerciante fue atacado a balazos mientras realizaba una transmisi\u00f3n en vivo a trav\u00e9s de la p\u00e1gina de Facebook \u201cHelados Nico\u201d, en la comunidad de Urireo.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>El hecho ocurri\u00f3 la ma\u00f1ana de este martes, cuando la v\u00edctima denunciaba el mal estado de las calles del lugar.<\/strong><\/p>\n\n\n\n<p><strong>De acuerdo con los primeros reportes, el hombre, conocido en la zona por su labor social y sus denuncias ciudadanas, se encontraba grabando un video que superaba los 40 minutos de duraci\u00f3n.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Durante la transmisi\u00f3n, dos sujetos que viajaban a bordo de una motocicleta se acercaron por la espalda y le dispararon en repetidas ocasiones.<\/strong><\/p>\n\n\n\n<p><strong>Tras los disparos, los agresores huyeron con rumbo desconocido.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>La c\u00e1mara continu\u00f3 transmitiendo en directo, mostrando los momentos de tensi\u00f3n y desesperaci\u00f3n en los que vecinos y familiares intentaban auxiliar al comerciante, que permanec\u00eda malherido sobre el pavimento.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un comerciante fue atacado a balazos mientras realizaba una transmisi\u00f3n en vivo a trav\u00e9s de la p\u00e1gina de Facebook \u201cHelados Nico\u201d, en la comunidad de Urireo.&nbsp; El hecho ocurri\u00f3 la ma\u00f1ana de este martes, cuando la v\u00edctima denunciaba el mal estado de las calles del lugar. De acuerdo con los primeros reportes, el hombre, conocido&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8927,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-8923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guanajuato-rojo"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/8923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=8923"}],"version-history":[{"count":1,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/8923\/revisions"}],"predecessor-version":[{"id":8924,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/8923\/revisions\/8924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media\/8927"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=8923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=8923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=8923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}