{"id":7938,"date":"2025-08-22T00:54:03","date_gmt":"2025-08-22T00:54:03","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=7938"},"modified":"2025-08-22T00:54:03","modified_gmt":"2025-08-22T00:54:03","slug":"arranco-el-programa-estatal-de-entrega-de-utiles-escolares-en-abasolo","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/08\/22\/arranco-el-programa-estatal-de-entrega-de-utiles-escolares-en-abasolo\/","title":{"rendered":"Arranc\u00f3 el programa estatal de entrega de \u00fatiles escolares en Abasolo"},"content":{"rendered":"\n<p>En coordinaci\u00f3n con el Gobierno de la Gente, el presidente municipal Job Gallardo, junto con el Secretario de Educaci\u00f3n, Luis Ignacio S\u00e1nchez G\u00f3mez, dieron inicio al programa estatal de entrega de \u00fatiles escolares correspondiente a este a\u00f1o.<\/p>\n\n\n\n<p>Este programa beneficiar\u00e1 a casi 10 mil ni\u00f1os abasolenses, pertenecientes a todas las primarias p\u00fablicas del municipio, garantizando que los estudiantes cuenten con los materiales necesarios para un inicio de ciclo escolar exitoso.<\/p>\n\n\n\n<p>El presidente municipal, Job Gallardo, destac\u00f3 la importancia de impulsar la educaci\u00f3n y apoyar a las familias del municipio: \u201cInvertir en la educaci\u00f3n de nuestros ni\u00f1os es construir un futuro s\u00f3lido para Abasolo\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Con esta acci\u00f3n, el Gobierno Municipal reafirma su compromiso de trabajar de la mano con los programas estatales para garantizar que todos los ni\u00f1os tengan acceso a herramientas educativas de calidad.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En coordinaci\u00f3n con el Gobierno de la Gente, el presidente municipal Job Gallardo, junto con el Secretario de Educaci\u00f3n, Luis Ignacio S\u00e1nchez G\u00f3mez, dieron inicio al programa estatal de entrega de \u00fatiles escolares correspondiente a este a\u00f1o. Este programa beneficiar\u00e1 a casi 10 mil ni\u00f1os abasolenses, pertenecientes a todas las primarias p\u00fablicas del municipio, garantizando&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-7938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abasolo"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/7938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=7938"}],"version-history":[{"count":1,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/7938\/revisions"}],"predecessor-version":[{"id":7940,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/7938\/revisions\/7940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media\/7939"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=7938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=7938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=7938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}