{"id":455,"date":"2024-07-11T22:21:05","date_gmt":"2024-07-11T22:21:05","guid":{"rendered":"http:\/\/www.primerplanoirapuato.com\/?p=36135"},"modified":"2024-07-11T22:21:05","modified_gmt":"2024-07-11T22:21:05","slug":"conocen-ciudadanos-nuevas-instalaciones-de-c4-irapuato","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/07\/11\/conocen-ciudadanos-nuevas-instalaciones-de-c4-irapuato\/","title":{"rendered":"CONOCEN CIUDADANOS NUEVAS INSTALACIONES DE C4 IRAPUATO"},"content":{"rendered":"\n<p>Integrantes de la sociedad civil&nbsp;conocieron las mejores en infraestructura y equipo del Centro de Comando, Control, Comunicaci\u00f3n y Computo (C4), con&nbsp;la finalidad de promover la participaci\u00f3n de la sociedad en&nbsp;materia de seguridad.<\/p>\n\n\n\n<p>Empresarios y ciudadanos de diversos sectores de la ciudad&nbsp;han acudido&nbsp;al&nbsp;C4&nbsp;de la&nbsp;Secretar\u00eda de Seguridad Ciudadana (SSCI) para conocer su funcionamiento, las acciones que el personal realiza&nbsp;y los beneficios que recibe la ciudadan\u00eda con&nbsp;las&nbsp;actualizaciones&nbsp;tecnol\u00f3gicas que recientemente se implementaron.<\/p>\n\n\n\n<p>En este recinto, se realiz\u00f3 la inversi\u00f3n de 250 millones de pesos para la renovaci\u00f3n de infraestructura tecnol\u00f3gica, instalaciones, 100 nuevos puntos de monitoreo Inteligente&nbsp;con 400 nuevas c\u00e1maras, 30 c\u00e1maras lectoras de&nbsp;placa, la puesta en marcha de un arco carretero, entre otras acciones gestionadas e impulsadas por el Gobierno Municipal.<\/p>\n\n\n\n<p>Ricardo Benavides Hern\u00e1ndez, secretario de&nbsp;Seguridad&nbsp;Ciudadana&nbsp;comparti\u00f3 a las&nbsp;y los irapuatenses&nbsp;que esta obra ha sido de gran ayuda para&nbsp;mejorar la atenci\u00f3n&nbsp;que se brinda a la sociedad en materia de seguridad y&nbsp;vigilancia; as\u00ed como en las diferentes emergencias que se presentan en el municipio.<\/p>\n\n\n\n<p>As\u00ed mismo,&nbsp;resalt\u00f3 que,&nbsp;con estas acciones de mejora, tambi\u00e9n se ha beneficiado a los&nbsp;colaboradores&nbsp;del&nbsp;C4, con&nbsp;la dignificaci\u00f3n de los espacios de trabajo y&nbsp;convivencia; as\u00ed como la creaci\u00f3n de un cuarto de contenci\u00f3n psicol\u00f3gico y control del estr\u00e9s.<\/p>\n\n\n\n<p>Adem\u00e1s,&nbsp;conocieron de cerca la labor que el personal del Sistema de Emergencias 9-1-1 realiza para brindar atenci\u00f3n a la ciudadan\u00eda, la recepci\u00f3n de llamadas, la vinculaci\u00f3n con los cuerpos de emergencia y seguridad, el despacho de los servicios y unidades y la atenci\u00f3n que&nbsp;los elementos&nbsp;realizan en calle.&nbsp;<\/p>\n\n\n\n<p><a><\/a>Con las actualizaciones en la infraestructura tecnol\u00f3gica de sus diversas \u00e1reas y la preparaci\u00f3n&nbsp;continua de todo su personal, la Secretar\u00eda de Seguridad Ciudadana mantiene el compromiso de mejorar la atenci\u00f3n de protecci\u00f3n y vigilancia para las y los irapuatenses.&nbsp;<\/p>\n\n\n\n<p>Con este objetivo el Gobierno Municipal a trav\u00e9s de la Secretar\u00eda de Seguridad Ciudadana convoca a la poblaci\u00f3n a ser parte de C4 con el reclutamiento de personal para las plazas de Operador de Video vigilancia y Operad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrantes de la sociedad civil&nbsp;conocieron las mejores en infraestructura y equipo del Centro de Comando, Control, Comunicaci\u00f3n y Computo (C4), con&nbsp;la finalidad de promover la participaci\u00f3n de la sociedad en&nbsp;materia de seguridad. Empresarios y ciudadanos de diversos sectores de la ciudad&nbsp;han acudido&nbsp;al&nbsp;C4&nbsp;de la&nbsp;Secretar\u00eda de Seguridad Ciudadana (SSCI) para conocer su funcionamiento, las acciones que el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-irapuato"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=455"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}