{"id":3274,"date":"2025-01-15T20:31:00","date_gmt":"2025-01-15T20:31:00","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=3274"},"modified":"2025-01-15T20:31:00","modified_gmt":"2025-01-15T20:31:00","slug":"aprueban-gppan-y-rpprd-lista-de-candidatas-y-candidatos-para-ocupar-la-titularidad-de-la-fiscalia-general-del-estado","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/01\/15\/aprueban-gppan-y-rpprd-lista-de-candidatas-y-candidatos-para-ocupar-la-titularidad-de-la-fiscalia-general-del-estado\/","title":{"rendered":"Aprueban GPPAN y RPPRD lista de candidatas y candidatos para ocupar la titularidad de la Fiscal\u00eda General del Estado"},"content":{"rendered":"\n<p>Con votos a favor por parte del Grupo Parlamentario del PAN y de la Representaci\u00f3n Parlamentaria del PRD, se aprob\u00f3 la lista de candidatas y candidatos para ocupar la titularidad de la Fiscal\u00eda General del Estado, la cual ser\u00e1 enviada a la gobernadora del estado, Libia Dennise Garc\u00eda Mu\u00f1oz Ledo.<\/p>\n\n\n\n<p>Dicha lista formulada por las diputadas y los diputados que integran la Junta de Gobierno y Coordinaci\u00f3n Pol\u00edtica qued\u00f3 conformada de la siguiente manera: Juan Manuel \u00c1lvarez Gonz\u00e1lez, Gerardo V\u00e1zquez Alatriste, Zuc\u00e9 Anastacia Hern\u00e1ndez Mart\u00ednez, Carlos D\u00edaz Abrego, Julio C\u00e9sar Maldonado Ledesma, Antonio Mendoza Ch\u00e1vez, Dalia Ram\u00edrez Delgado, Israel Aguado Silva, Ricardo Vilchis Contreras.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que una vez que el Poder Ejecutivo estatal reciba el listado contar\u00e1 con diez d\u00edas para formular una terna y enviarla al Congreso del Estado, posteriormente en un plazo de diez d\u00edas la Diputaci\u00f3n Permanente la turnar\u00e1 a la Comisi\u00f3n de Justicia, para que se lleve a cabo el an\u00e1lisis correspondiente y emita un dictamen.<\/p>\n\n\n\n<p>Una vez concluido dicho proceso, la Diputaci\u00f3n Permanente convocar\u00e1 a otro periodo extraordinario de sesiones para que se lleve a cabo la discusi\u00f3n y votaci\u00f3n del dictamen y se elija a quien ocupar\u00e1 la titularidad de la Fiscal\u00eda General del Estado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con votos a favor por parte del Grupo Parlamentario del PAN y de la Representaci\u00f3n Parlamentaria del PRD, se aprob\u00f3 la lista de candidatas y candidatos para ocupar la titularidad de la Fiscal\u00eda General del Estado, la cual ser\u00e1 enviada a la gobernadora del estado, Libia Dennise Garc\u00eda Mu\u00f1oz Ledo. Dicha lista formulada por las&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/3274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=3274"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/3274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=3274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=3274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=3274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}