{"id":3244,"date":"2025-01-14T20:55:16","date_gmt":"2025-01-14T20:55:16","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=3244"},"modified":"2025-01-14T20:55:16","modified_gmt":"2025-01-14T20:55:16","slug":"confirmadas-dos-detenciones-vinculadas-a-extorsiones-en-irapuato-gobernadora-libia-garcia","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/01\/14\/confirmadas-dos-detenciones-vinculadas-a-extorsiones-en-irapuato-gobernadora-libia-garcia\/","title":{"rendered":"Confirmadas dos detenciones vinculadas a extorsiones en Irapuato: Gobernadora Libia Garc\u00eda"},"content":{"rendered":"\n<p>La gobernadora de Guanajuato, Libia Denisse Garc\u00eda Mu\u00f1oz Ledo, inform\u00f3 sobre la detenci\u00f3n de dos personas presuntamente involucradas en extorsiones a comerciantes de Irapuato.<\/p>\n\n\n\n<p>En una reciente entrevista, Garc\u00eda Mu\u00f1oz Ledo confirm\u00f3 que las detenciones, realizadas este fin de semana, son parte de las acciones implementadas en la estrategia de seguridad de la regi\u00f3n.&nbsp;<\/p>\n\n\n\n<p>\u201cHubo este fin de semana detenciones importantes, dos detenciones que creemos, presuntamente, pueden estar relacionadas con este tipo de extorsiones\u201d, indic\u00f3 la mandataria.<\/p>\n\n\n\n<p>Asegur\u00f3 que las investigaciones continuar\u00e1n bajo la supervisi\u00f3n de la Fiscal\u00eda General del Estado y las autoridades locales, con el objetivo de esclarecer los hechos ocurridos en los \u00faltimos d\u00edas.&nbsp;<\/p>\n\n\n\n<p>Garc\u00eda Mu\u00f1oz Ledo destac\u00f3 que las detenciones son el resultado del trabajo conjunto entre las autoridades de seguridad p\u00fablica y las fuerzas de \u00e9lite encargadas de ejecutar la estrategia integral para combatir el crimen organizado en Guanajuato.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gobernadora de Guanajuato, Libia Denisse Garc\u00eda Mu\u00f1oz Ledo, inform\u00f3 sobre la detenci\u00f3n de dos personas presuntamente involucradas en extorsiones a comerciantes de Irapuato. En una reciente entrevista, Garc\u00eda Mu\u00f1oz Ledo confirm\u00f3 que las detenciones, realizadas este fin de semana, son parte de las acciones implementadas en la estrategia de seguridad de la regi\u00f3n.&nbsp; \u201cHubo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3247,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/3244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=3244"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/3244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=3244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=3244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=3244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}