{"id":3181,"date":"2025-01-11T18:59:59","date_gmt":"2025-01-11T18:59:59","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=3181"},"modified":"2025-01-11T18:59:59","modified_gmt":"2025-01-11T18:59:59","slug":"ejecutan-a-limpiador-de-vidrios-de-coche-en-celaya","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/01\/11\/ejecutan-a-limpiador-de-vidrios-de-coche-en-celaya\/","title":{"rendered":"Ejecutan a limpiador de vidrios de coche en Celaya"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Un joven, presuntamente limpiaparabrisas, fue asesinado a balazos la ma\u00f1ana de este s\u00e1bado en la avenida Francisco Ju\u00e1rez, casi esquina con el bulevar Adolfo L\u00f3pez Mateos, una de las zonas m\u00e1s transitadas de la ciudad.<\/p>\n\n\n\n<p>El ataque ocurri\u00f3 alrededor de las 10:45 a.m., desatando el p\u00e1nico entre automovilistas y transe\u00fantes. Testigos reportaron haber escuchado entre cinco y seis disparos. El joven, de entre 20 y 25 a\u00f1os, cay\u00f3 abatido en el lugar con heridas visibles de bala en la cabeza.<\/p>\n\n\n\n<p>Elementos de la Guardia Nacional y polic\u00edas municipales acudieron al sitio tras el reporte al 911. Param\u00e9dicos de la Cruz Roja confirmaron que el joven ya no presentaba signos vitales. La zona fue acordonada mientras agentes de la Fiscal\u00eda General del Estado realizaban las investigaciones correspondientes y recolectaban evidencias.<\/p>\n\n\n\n<p>El tr\u00e1fico vehicular fue desviado durante varias horas para permitir las diligencias. Al t\u00e9rmino de estas, el cuerpo fue trasladado al Servicio M\u00e9dico Forense para la necropsia de ley. Autoridades contin\u00faan las investigaciones para esclarecer el crimen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un joven, presuntamente limpiaparabrisas, fue asesinado a balazos la ma\u00f1ana de este s\u00e1bado en la avenida Francisco Ju\u00e1rez, casi esquina con el bulevar Adolfo L\u00f3pez Mateos, una de las zonas m\u00e1s transitadas de la ciudad. El ataque ocurri\u00f3 alrededor de las 10:45 a.m., desatando el p\u00e1nico entre automovilistas y transe\u00fantes. Testigos reportaron haber escuchado entre&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3182,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/3181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=3181"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/3181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=3181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=3181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=3181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}