{"id":2300,"date":"2024-11-08T03:57:45","date_gmt":"2024-11-08T03:57:45","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=2300"},"modified":"2024-11-08T03:57:45","modified_gmt":"2024-11-08T03:57:45","slug":"ataques-armados-en-irapuato-dejan-un-muerto-y-tres-heridos","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/11\/08\/ataques-armados-en-irapuato-dejan-un-muerto-y-tres-heridos\/","title":{"rendered":"Ataques armados en Irapuato dejan un muerto y tres heridos"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Dos ataques armados registrados la noche del jueves en Irapuato dejaron un saldo de un muerto y tres heridos. <br>El primer incidente ocurri\u00f3 en la colonia 12 de Diciembre, donde un hombre fue asesinado dentro de un negocio.<\/p>\n\n\n\n<p> Casi simult\u00e1neamente, en la colonia 24 de Diciembre, tres hombres resultaron heridos en otro ataque.<\/p>\n\n\n\n<p> Ambos sitios fueron acordonados y la Fiscal\u00eda General del Estado inici\u00f3 las investigaciones para esclarecer los hechos y determinar si hay conexi\u00f3n entre ambos ataques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos ataques armados registrados la noche del jueves en Irapuato dejaron un saldo de un muerto y tres heridos. El primer incidente ocurri\u00f3 en la colonia 12 de Diciembre, donde un hombre fue asesinado dentro de un negocio. Casi simult\u00e1neamente, en la colonia 24 de Diciembre, tres hombres resultaron heridos en otro ataque. Ambos sitios&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2301,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/2300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=2300"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/2300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=2300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=2300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=2300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}