{"id":1498,"date":"2024-09-20T22:44:01","date_gmt":"2024-09-20T22:44:01","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1498"},"modified":"2024-09-20T22:44:01","modified_gmt":"2024-09-20T22:44:01","slug":"dif-irapuato-presenta-su-tercer-informe-de-actividades-destacando-apoyo-a-familias-y-grupos-vulnerables","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/20\/dif-irapuato-presenta-su-tercer-informe-de-actividades-destacando-apoyo-a-familias-y-grupos-vulnerables\/","title":{"rendered":"DIF Irapuato presenta su Tercer Informe de Actividades, destacando apoyo a familias y grupos vulnerables"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>En su Tercer Informe de Actividades, Valeria Alfaro Garc\u00eda, presidenta del DIF Irapuato, resalt\u00f3 los logros obtenidos en beneficio de las familias, adultos mayores, personas con discapacidad, ni\u00f1as, ni\u00f1os y adolescentes. <br><\/p>\n\n\n\n<p>Con un enfoque en pol\u00edticas p\u00fablicas con perspectiva familiar, se destac\u00f3 el programa \u00abCreciendo con valores\u00bb y el reconocimiento estatal por su compromiso con la infancia.<\/p>\n\n\n\n<p>Adem\u00e1s, el DIF ha ofrecido m\u00e1s de 37 mil sesiones de rehabilitaci\u00f3n en el Gimnasio Paral\u00edmpico Regional y adapt\u00f3 la Feria de las Fresas para personas con discapacidad, siendo la primera en Latinoam\u00e9rica en contar con un distintivo de turismo inclusivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su Tercer Informe de Actividades, Valeria Alfaro Garc\u00eda, presidenta del DIF Irapuato, resalt\u00f3 los logros obtenidos en beneficio de las familias, adultos mayores, personas con discapacidad, ni\u00f1as, ni\u00f1os y adolescentes. Con un enfoque en pol\u00edticas p\u00fablicas con perspectiva familiar, se destac\u00f3 el programa \u00abCreciendo con valores\u00bb y el reconocimiento estatal por su compromiso con&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1498"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}