{"id":1483,"date":"2024-09-19T21:29:37","date_gmt":"2024-09-19T21:29:37","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1483"},"modified":"2024-09-19T21:29:37","modified_gmt":"2024-09-19T21:29:37","slug":"participan-irapuatenses-en-simulacro-nacional-de-sismo","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/19\/participan-irapuatenses-en-simulacro-nacional-de-sismo\/","title":{"rendered":"PARTICIPAN IRAPUATENSES EN SIMULACRO NACIONAL DE SISMO"},"content":{"rendered":"\n<p>Con saldo blanco concluy\u00f3 el Simulacro Nacional de Sismo en la ciudad, report\u00f3 la Coordinaci\u00f3n Municipal de Protecci\u00f3n Civil y de Bomberos.<\/p>\n\n\n\n<p>El simulacro con hip\u00f3tesis de sismo 7.5 en escala de Richter con epicentro en Guerrero, se realiz\u00f3 en punto de las 11 de la ma\u00f1ana con la participaci\u00f3n de m\u00e1s de 4 mil 72 irapuatenses que de manera ordenada evacuaron instalaciones de edificios p\u00fablicos, empresas, plazas comerciales e instituciones educativas del sector p\u00fablico y privado, entre otras.<\/p>\n\n\n\n<p>Israel Mart\u00ednez Negrete, coordinador de Protecci\u00f3n Civil y de Bomberos, inform\u00f3 que los resultados de este ejercicio fueron positivos al contar con una buena participaci\u00f3n en la que la ciudadan\u00eda se comport\u00f3, por lo que, hizo un llamado a continuar con estas actividades que tienen como objetivo estar preparados ante un movimiento tel\u00farico real.<\/p>\n\n\n\n<p>\u201cEstamos muy contentos, primero de la participaci\u00f3n de la ciudadan\u00eda, vemos que ya est\u00e1n m\u00e1s ocupados en aprender, lo que es la cultura de protecci\u00f3n civil, que est\u00e1n preocupados en la llegada de un incidente, tuvimos muy buena respuesta de much\u00edsimos lugares aqu\u00ed en Irapuato\u201d, coment\u00f3.<\/p>\n\n\n\n<p>El funcionario municipal agreg\u00f3 que, en busca de mejorar los procesos de cada instituci\u00f3n participante, se reunir\u00e1n con los brigadistas de cada \u00e1rea, para evaluar e identificar las \u00e1reas de oportunidad y mejorarlas para los pr\u00f3ximos simulacros.<\/p>\n\n\n\n<p>Este a\u00f1o se inscribieron 41 establecimientos p\u00fablicos y privados, no obstante, el simulacro se llev\u00f3 a cabo en otros sitios en los que se activaron las brigadas internas de Protecci\u00f3n Civil.<\/p>\n\n\n\n<p>Durante el simulacro, personal de la Coordinaci\u00f3n Municipal de Protecci\u00f3n Civil fungi\u00f3 como observador dando fe del evento, y realizaron observaciones a los encargados de brigadas sobre el protocolo efectuado, tiempos de evacuaci\u00f3n y acciones de prevenci\u00f3n implementadas.<\/p>\n\n\n\n<p>En este ejercicio las acciones fueron encabezadas por personal de Protecci\u00f3n Civil y Bomberos, en coordinaci\u00f3n con integrantes de Tr\u00e1nsito, Polic\u00eda Municipal y param\u00e9dicos de Cruz Roja, quienes apoyaron en los lugares donde se llev\u00f3 a cabo el simulacro con el cierre de vialidades y seguridad en los sitios.<\/p>\n\n\n\n<p>La Secretar\u00eda de Seguridad Ciudadana Municipal hizo un llamado a la ciudadan\u00eda a continuar participando en estos ejercicios, conformar brigadas internas y sumarse a estas acciones para contar con una cultura de prevenci\u00f3n efectiva ante posibles siniestros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con saldo blanco concluy\u00f3 el Simulacro Nacional de Sismo en la ciudad, report\u00f3 la Coordinaci\u00f3n Municipal de Protecci\u00f3n Civil y de Bomberos. El simulacro con hip\u00f3tesis de sismo 7.5 en escala de Richter con epicentro en Guerrero, se realiz\u00f3 en punto de las 11 de la ma\u00f1ana con la participaci\u00f3n de m\u00e1s de 4 mil&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1484,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1483"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}