{"id":1446,"date":"2024-09-17T21:53:20","date_gmt":"2024-09-17T21:53:20","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1446"},"modified":"2024-09-17T21:53:20","modified_gmt":"2024-09-17T21:53:20","slug":"ofreceran-restaurantes-precios-accesibles-en-irapuato","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/17\/ofreceran-restaurantes-precios-accesibles-en-irapuato\/","title":{"rendered":"Ofrecer\u00e1n restaurantes precios accesibles en Irapuato"},"content":{"rendered":"\n<p>La segunda edici\u00f3n del &#8216;Irapuato Restaurant Week&#8217;, se realizar\u00e1 del 23 al 29 de septiembre en 42 restaurantes, que ofrecer\u00e1n precios accesibles para todo el p\u00fablico.<\/p>\n\n\n\n<p>Sergio Santos Navarro, director de la C\u00e1mara Nacional de la Industria Restaurantera en Irapuato (Canirac), se\u00f1al\u00f3 que esta iniciativa denominada &#8216;La Semana M\u00e1s Barata del A\u00f1o&#8217;, se realiza a nivel nacional con la finalidad de apoyar la econom\u00eda familiar e impulsar el comercio local.<\/p>\n\n\n\n<p>\u00abEn estos establecimientos tendremos un men\u00fa general de 159 pesos y en algunos una opci\u00f3n de 259, incluyen comida completa de plato fuerte, postre y una bebida\u00bb, apunt\u00f3.<\/p>\n\n\n\n<p>H\u00e9ctor Mu\u00f1oz, director de Econom\u00eda y Turismo, invit\u00f3 a la ciudadan\u00eda a participar y degustar una amplia variedad de platillos durante esta semana.<\/p>\n\n\n\n<p>\u00abEs un proyecto de la Canirac Nacional que aterriza en Irapuato por segunda ocasi\u00f3n, el municipio de Irapuato est\u00e1 muy contento de seguir colaborando, tenemos proyectos en puerta y agradecemos la colaboraci\u00f3n del sector\u00bb, puntualiz\u00f3.<\/p>\n\n\n\n<p>Cabe destacar que, luego de la pandemia, la econom\u00eda se reactiv\u00f3 y el sector restaurantero en Irapuato aument\u00f3 en un 13 por ciento.<\/p>\n\n\n\n<p>La ciudadan\u00eda puede conocer los restaurantes participantes y sus men\u00fas a trav\u00e9s de las redes sociales oficiales de la Canirac y acudir a disfrutar de estos beneficios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La segunda edici\u00f3n del &#8216;Irapuato Restaurant Week&#8217;, se realizar\u00e1 del 23 al 29 de septiembre en 42 restaurantes, que ofrecer\u00e1n precios accesibles para todo el p\u00fablico. Sergio Santos Navarro, director de la C\u00e1mara Nacional de la Industria Restaurantera en Irapuato (Canirac), se\u00f1al\u00f3 que esta iniciativa denominada &#8216;La Semana M\u00e1s Barata del A\u00f1o&#8217;, se realiza a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1447,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1446"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}