{"id":1443,"date":"2024-09-17T20:11:27","date_gmt":"2024-09-17T20:11:27","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1443"},"modified":"2024-09-17T20:11:27","modified_gmt":"2024-09-17T20:11:27","slug":"apoyan-a-estudiantes-con-becas-municipales","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/17\/apoyan-a-estudiantes-con-becas-municipales\/","title":{"rendered":"Apoyan a estudiantes con Becas Municipales"},"content":{"rendered":"\n<p>Un total de 661 alumnos de la lista de espera del programa&nbsp;\u2018Apoyos Econ\u00f3micos Educativos\u2019,&nbsp;ser\u00e1n beneficiados tras la reasignaci\u00f3n del recurso.<\/p>\n\n\n\n<p>La&nbsp;directora de Educaci\u00f3n del Gobierno de Irapuato, Joyce Guerrero Barajas, explic\u00f3 que en total se destinar\u00e1 un mill\u00f3n 325 mil pesos en beneficio de estudiantes de primaria, secundaria y universidad.<\/p>\n\n\n\n<p>\u201cEl d\u00eda de hoy sali\u00f3 publicado el listado de 661 beneficiados&nbsp;de la lista de espera que ten\u00edamos de 723 alumnos (\u2026) estos apoyos se van a pagar el pr\u00f3ximo d\u00eda 30 de septiembre en la Plaza del Artista\u201d,explic\u00f3.<\/p>\n\n\n\n<p>A los beneficiarios de primaria se les&nbsp;entregar\u00e1&nbsp;una beca de 2 mil pesos, a los de secundaria de 3 mil pesos, mientras que a los de universidad se les pagar\u00e1n&nbsp;4 mil pesos. La persona autorizada para cobrar la beca deber\u00e1 presentarse el 30 de septiembre a las 11:00&nbsp;de la ma\u00f1ana&nbsp;en la Plaza del Artista, con identificaci\u00f3n oficial y una copia.<\/p>\n\n\n\n<p>La lista de los beneficiarios&nbsp;se puede consultar&nbsp;en&nbsp;<a href=\"https:\/\/www.irapuato.gob.mx\/becas\/\">www.irapuato.gob.mx\/becas\/#asignacionremanente<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un total de 661 alumnos de la lista de espera del programa&nbsp;\u2018Apoyos Econ\u00f3micos Educativos\u2019,&nbsp;ser\u00e1n beneficiados tras la reasignaci\u00f3n del recurso. La&nbsp;directora de Educaci\u00f3n del Gobierno de Irapuato, Joyce Guerrero Barajas, explic\u00f3 que en total se destinar\u00e1 un mill\u00f3n 325 mil pesos en beneficio de estudiantes de primaria, secundaria y universidad. \u201cEl d\u00eda de hoy sali\u00f3&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}