{"id":13949,"date":"2026-05-13T00:36:24","date_gmt":"2026-05-13T00:36:24","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=13949"},"modified":"2026-05-13T00:36:24","modified_gmt":"2026-05-13T00:36:24","slug":"colectivo-de-busqueda-localiza-tres-osamentas-en-camino-rural-de-irapuato","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2026\/05\/13\/colectivo-de-busqueda-localiza-tres-osamentas-en-camino-rural-de-irapuato\/","title":{"rendered":"Colectivo de b\u00fasqueda localiza tres osamentas en camino rural de Irapuato"},"content":{"rendered":"\n<p><strong>Integrantes del colectivo \u201cHasta Encontrarte\u201d localizaron tres cuerpos en estado de descomposici\u00f3n durante una jornada de b\u00fasqueda realizada en una zona rural del municipio de Irapuato.<\/strong><\/p>\n\n\n\n<p><strong>El hallazgo ocurri\u00f3 sobre un camino terracero ubicado entre las comunidades de San Antonio Texas y Buenos Aires, en un \u00e1rea despoblada donde las buscadoras realizaron trabajos de exploraci\u00f3n desde temprana hora.<\/strong><\/p>\n\n\n\n<p><strong>De manera preliminar, se inform\u00f3 que los restos corresponden a dos hombres y una mujer.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>La activista&nbsp;<\/strong><strong>Karla Mart\u00ednez<\/strong><strong>&nbsp;confirm\u00f3 los hechos mediante redes sociales y se\u00f1al\u00f3 que la b\u00fasqueda continuaba en el lugar debido a que no se descartaba el hallazgo de m\u00e1s osamentas.<\/strong><\/p>\n\n\n\n<p><strong>Peritos y agentes de investigaci\u00f3n de la Fiscal\u00eda General del Estado procesan la escena y llevar\u00e1n a cabo los estudios forenses para determinar identidad y causas de muerte.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrantes del colectivo \u201cHasta Encontrarte\u201d localizaron tres cuerpos en estado de descomposici\u00f3n durante una jornada de b\u00fasqueda realizada en una zona rural del municipio de Irapuato. El hallazgo ocurri\u00f3 sobre un camino terracero ubicado entre las comunidades de San Antonio Texas y Buenos Aires, en un \u00e1rea despoblada donde las buscadoras realizaron trabajos de exploraci\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13950,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-13949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-irapuato"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/13949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=13949"}],"version-history":[{"count":1,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/13949\/revisions"}],"predecessor-version":[{"id":13952,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/13949\/revisions\/13952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media\/13950"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=13949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=13949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=13949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}