{"id":1370,"date":"2024-09-13T01:24:19","date_gmt":"2024-09-13T01:24:19","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1370"},"modified":"2024-09-13T01:24:19","modified_gmt":"2024-09-13T01:24:19","slug":"fidesseg-no-desaparecera-en-mi-administracion-diego","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/13\/fidesseg-no-desaparecera-en-mi-administracion-diego\/","title":{"rendered":"FIDESSEG no desaparecer\u00e1 en mi administraci\u00f3n: Diego"},"content":{"rendered":"\n<p>El gobernador de Guanajuato, Diego Sinhu\u00e9 Rodr\u00edguez Vallejo, asegur\u00f3 que el fideicomiso FIDESSEG no desaparecer\u00e1 durante su administraci\u00f3n, respondiendo a las preocupaciones de empresarios y asociaciones civiles. <br>Explic\u00f3 que el exhorto para eliminar el fideicomiso provino del Congreso del Estado y no de su gobierno.<\/p>\n\n\n\n<p> A pesar de haber repetido en varias ocasiones que el FIDESSEG seguir\u00e1 vigente, el gobernador se mostr\u00f3 sorprendido por la inquietud del sector empresarial, subrayando que sus declaraciones han sido claras y consistentes al respecto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de Guanajuato, Diego Sinhu\u00e9 Rodr\u00edguez Vallejo, asegur\u00f3 que el fideicomiso FIDESSEG no desaparecer\u00e1 durante su administraci\u00f3n, respondiendo a las preocupaciones de empresarios y asociaciones civiles. Explic\u00f3 que el exhorto para eliminar el fideicomiso provino del Congreso del Estado y no de su gobierno. A pesar de haber repetido en varias ocasiones que el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1371,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1370"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}