{"id":1355,"date":"2024-09-11T20:41:01","date_gmt":"2024-09-11T20:41:01","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1355"},"modified":"2024-09-11T20:41:01","modified_gmt":"2024-09-11T20:41:01","slug":"piden-continuidad-del-fidesseg","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/11\/piden-continuidad-del-fidesseg\/","title":{"rendered":"PIDEN CONTINUIDAD DEL FIDESSEG"},"content":{"rendered":"\n<p><br>Este 11 de septiembre se llev\u00f3 a cabo el Primer Encuentro de Organizaciones de la Sociedad Civil en Guanajuato, donde se defendi\u00f3 el modelo de participaci\u00f3n ciudadana FIDESSEG.&nbsp;<\/p>\n\n\n\n<p>Diversas asociaciones civiles, fundaciones y organismos empresariales reafirmaron su apoyo a este modelo, que ha sido clave en promover la solidaridad y gestionar recursos para los sectores m\u00e1s vulnerables.<\/p>\n\n\n\n<p>Se destac\u00f3 la importancia de mantener este esquema como un pilar en la distribuci\u00f3n eficiente de los recursos derivados del impuesto sobre n\u00f3minas, y se subray\u00f3 la necesidad de fortalecer la transparencia y sensibilidad en cada acci\u00f3n de apoyo social.<\/p>\n\n\n\n<p>Finalmente, hicieron un llamado al gobernador Diego Sinhue Rodr\u00edguez Vallejo y a la gobernadora electa Libia Dennise Garc\u00eda Mu\u00f1oz Ledo para que participen en una reuni\u00f3n de trabajo conjunta, con el objetivo de perfeccionar el modelo y asegurar que los recursos lleguen a quienes m\u00e1s lo necesitan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 11 de septiembre se llev\u00f3 a cabo el Primer Encuentro de Organizaciones de la Sociedad Civil en Guanajuato, donde se defendi\u00f3 el modelo de participaci\u00f3n ciudadana FIDESSEG.&nbsp; Diversas asociaciones civiles, fundaciones y organismos empresariales reafirmaron su apoyo a este modelo, que ha sido clave en promover la solidaridad y gestionar recursos para los sectores&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1356,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1355"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}