{"id":1323,"date":"2024-09-08T17:23:16","date_gmt":"2024-09-08T17:23:16","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1323"},"modified":"2024-09-08T17:23:16","modified_gmt":"2024-09-08T17:23:16","slug":"localizan-posible-centro-de-distribucion-de-huachicol-en-penjamo-y-desmantelan-tomas-clandestinas-en-aratzipu","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/08\/localizan-posible-centro-de-distribucion-de-huachicol-en-penjamo-y-desmantelan-tomas-clandestinas-en-aratzipu\/","title":{"rendered":"Localizan posible centro de distribuci\u00f3n de huachicol en P\u00e9njamo y desmantelan tomas clandestinas en Aratzipu"},"content":{"rendered":"\n<p>En un operativo conjunto, elementos de la Guardia Nacional y personal de Petr\u00f3leos Mexicanos (PEMEX) localizaron lo que podr\u00eda ser un centro de distribuci\u00f3n de combustible robado, com\u00fanmente conocido como huachicol, en el municipio de P\u00e9njamo, Guanajuato.<\/p>\n\n\n\n<p>Durante el despliegue, se aseguraron cisternas y contenedores utilizados para almacenar el combustible de procedencia ilegal esto en el poblado de Aratzipu.<br><\/p>\n\n\n\n<p>Este hallazgo es parte de las acciones coordinadas entre las autoridades para combatir el robo de hidrocarburos en la regi\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n se inhabilitaron tres tomas clandestinas conectadas a ductos de PEMEX, las cuales representaban un grave riesgo para la seguridad p\u00fablica y el medio ambiente.<\/p>\n\n\n\n<p>Las autoridades informaron que continuar\u00e1n con las investigaciones para determinar si hay m\u00e1s involucrados en la operaci\u00f3n de estas redes de robo de combustible y aseguraron que reforzar\u00e1n la vigilancia en estas zonas para prevenir futuros incidentes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un operativo conjunto, elementos de la Guardia Nacional y personal de Petr\u00f3leos Mexicanos (PEMEX) localizaron lo que podr\u00eda ser un centro de distribuci\u00f3n de combustible robado, com\u00fanmente conocido como huachicol, en el municipio de P\u00e9njamo, Guanajuato. Durante el despliegue, se aseguraron cisternas y contenedores utilizados para almacenar el combustible de procedencia ilegal esto en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1324,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1323"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}