{"id":1311,"date":"2024-09-06T19:40:39","date_gmt":"2024-09-06T19:40:39","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1311"},"modified":"2024-09-06T19:40:39","modified_gmt":"2024-09-06T19:40:39","slug":"libia-pondra-a-los-mejores-en-seguridad-afirmo-cabeza-de-vaca","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/06\/libia-pondra-a-los-mejores-en-seguridad-afirmo-cabeza-de-vaca\/","title":{"rendered":"Libia pondr\u00e1 a los mejores en seguridad, afirm\u00f3 Cabeza de Vaca"},"content":{"rendered":"\n<p>El secretario de Seguridad de Guanajuato, \u00c1lvar Cabeza de Vaca, afirm\u00f3 que conoce a Libia Dennise, por lo que afirm\u00f3 que la gobernadora electa, pondr\u00e1 a los mejores perfiles en la SSPEG y en la fiscal\u00eda estatal.<\/p>\n\n\n\n<p>En entrevista, el funcionario dijo que Libia no se va a equivocar y dej\u00f3 en claro que despu\u00e9s de 12 a\u00f1os, se har\u00e1 a un lado la Secretar\u00eda de Seguridad P\u00fablica.<\/p>\n\n\n\n<p>Cabeza de Vaca coment\u00f3 que cumpli\u00f3, dando resultados en materia de incautaci\u00f3n de drogas y con la certificaci\u00f3n policial.<\/p>\n\n\n\n<p>El secretario precis\u00f3 que a diario hay un actuar de la Polic\u00eda Estatal con una efectividad del 90% en intervenciones a diario.<\/p>\n\n\n\n<p>\u00abQueda una Secretar\u00eda muy fuerte y dando resultados a diario, yo no dejo pendientes, el pendiente es del de diario, el pendiente ser\u00e1 para quien llegue, de seguir trabajando\u00bb, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Seguridad de Guanajuato, \u00c1lvar Cabeza de Vaca, afirm\u00f3 que conoce a Libia Dennise, por lo que afirm\u00f3 que la gobernadora electa, pondr\u00e1 a los mejores perfiles en la SSPEG y en la fiscal\u00eda estatal. En entrevista, el funcionario dijo que Libia no se va a equivocar y dej\u00f3 en claro que despu\u00e9s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1312,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1311"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}