{"id":1290,"date":"2024-09-05T19:53:33","date_gmt":"2024-09-05T19:53:33","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=1290"},"modified":"2024-09-05T19:53:33","modified_gmt":"2024-09-05T19:53:33","slug":"irapuato-mantendra-la-pirotecnia-en-fiestas-patrias-asegura-la-alcaldesa","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2024\/09\/05\/irapuato-mantendra-la-pirotecnia-en-fiestas-patrias-asegura-la-alcaldesa\/","title":{"rendered":"Irapuato mantendr\u00e1 la pirotecnia en Fiestas Patrias, asegura la Alcaldesa"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>La alcaldesa de Irapuato, Lorena Alfaro Garc\u00eda, confirm\u00f3 que el gobierno municipal recurrir\u00e1 al uso de pirotecnia para los festejos del 15 de septiembre. <\/p>\n\n\n\n<p>A pesar de los esfuerzos por promover alternativas m\u00e1s seguras, Alfaro Garc\u00eda afirm\u00f3 que es probable que se mantenga la tradici\u00f3n de los fuegos artificiales debido a su importancia cultural.<\/p>\n\n\n\n<p>\u201cEstamos promoviendo que no se utilice la pirotecnia, pero este d\u00eda en particular es com\u00fan que se contin\u00fae con esta tradici\u00f3n\u201d, declar\u00f3 la alcaldesa, subrayando que el 15 de septiembre es una fiesta tradicional para todos los mexicanos.<\/p>\n\n\n\n<p> A pesar de los riesgos asociados con la pirotecnia, Alfaro Garc\u00eda destac\u00f3 que la celebraci\u00f3n del Grito de Independencia se llevar\u00e1 a cabo con el uso de fuegos artificiales, manteniendo as\u00ed una costumbre arraigada en las festividades patrias de Irapuato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La alcaldesa de Irapuato, Lorena Alfaro Garc\u00eda, confirm\u00f3 que el gobierno municipal recurrir\u00e1 al uso de pirotecnia para los festejos del 15 de septiembre. A pesar de los esfuerzos por promover alternativas m\u00e1s seguras, Alfaro Garc\u00eda afirm\u00f3 que es probable que se mantenga la tradici\u00f3n de los fuegos artificiales debido a su importancia cultural. \u201cEstamos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1291,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=1290"}],"version-history":[{"count":0,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/1290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=1290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=1290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=1290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}