{"id":10705,"date":"2025-12-12T02:56:22","date_gmt":"2025-12-12T02:56:22","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=10705"},"modified":"2025-12-12T02:56:22","modified_gmt":"2025-12-12T02:56:22","slug":"reconoce-yozajamby-molina-la-labor-del-magisterio-en-la-formacion-de-la-sociedad","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/12\/12\/reconoce-yozajamby-molina-la-labor-del-magisterio-en-la-formacion-de-la-sociedad\/","title":{"rendered":"Reconoce Yozajamby Molina la labor del magisterio en la formaci\u00f3n de la sociedad"},"content":{"rendered":"\n<p>La presidenta municipal de P\u00e9njamo, Yozajamby Molina, encabez\u00f3 la tradicional posada del magisterio de la Secci\u00f3n 45 del SNTE, realizada en el Bodeg\u00f3n Dolce Vita de la Tequilera Corralejo. Al encuentro asistieron docentes de P\u00e9njamo, Abasolo, Cuer\u00e1maro y Huan\u00edmaro, quienes compartieron una convivencia marcada por la m\u00fasica, la unidad y el compa\u00f1erismo.<\/p>\n\n\n\n<p>Molina estuvo acompa\u00f1ada por el regidor Javier P\u00e9rez y por Jonathan Joya de la Sancha, secretario regional de la Secci\u00f3n 45, quienes participaron en las actividades organizadas para el personal educativo. Durante la celebraci\u00f3n se llevaron a cabo din\u00e1micas y un sorteo de obsequios que fortalecieron el ambiente festivo.<\/p>\n\n\n\n<p>En su mensaje, la alcaldesa resalt\u00f3 la importancia del magisterio en el desarrollo de la regi\u00f3n. \u201cEstar en este lugar, rodeados de industria y de historia, me hace pensar en lo que construimos a diario, en sus aulas se construye el futuro de la regi\u00f3n\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El evento concluy\u00f3 con un reconocimiento a la dedicaci\u00f3n de quienes, desde las aulas, impulsan la formaci\u00f3n y el crecimiento de las nuevas generaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta municipal de P\u00e9njamo, Yozajamby Molina, encabez\u00f3 la tradicional posada del magisterio de la Secci\u00f3n 45 del SNTE, realizada en el Bodeg\u00f3n Dolce Vita de la Tequilera Corralejo. Al encuentro asistieron docentes de P\u00e9njamo, Abasolo, Cuer\u00e1maro y Huan\u00edmaro, quienes compartieron una convivencia marcada por la m\u00fasica, la unidad y el compa\u00f1erismo. Molina estuvo acompa\u00f1ada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10706,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-10705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/10705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=10705"}],"version-history":[{"count":1,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/10705\/revisions"}],"predecessor-version":[{"id":10707,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/10705\/revisions\/10707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media\/10706"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=10705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=10705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=10705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}