{"id":10672,"date":"2025-12-10T18:24:45","date_gmt":"2025-12-10T18:24:45","guid":{"rendered":"https:\/\/primerplanoirapuato.com\/?p=10672"},"modified":"2025-12-10T18:24:45","modified_gmt":"2025-12-10T18:24:45","slug":"detenciones-no-son-parte-de-la-estrategia-ssci","status":"publish","type":"post","link":"https:\/\/primerplanoirapuato.com\/index.php\/2025\/12\/10\/detenciones-no-son-parte-de-la-estrategia-ssci\/","title":{"rendered":"Detenciones no son parte de la estrategia: SSCI"},"content":{"rendered":"\n<p>Cuestionada sobre la baja en las detenciones que hubo en noviembre por parte de la Polic\u00eda Municipal de Irapuato, la secretaria de Seguridad, Consuelo Cruz Galindo afirm\u00f3 que las aprehensiones no son parte de la estrategia, sino resultados.<\/p>\n\n\n\n<p>La funcionaria expuso que la misma din\u00e1mica de trabajo los obliga a atender otros hechos, como todos los eventos que hubo en noviembre.<\/p>\n\n\n\n<p>\u201cLas detenciones s\u00ed hay, hay tiros certeros, trabajamos con objetivos, que es la diferencia, habilitamos el \u00e1rea de inteligencia\u201d, dijo.<\/p>\n\n\n\n<p>La secretaria coment\u00f3 que tan solo la semana pasada hubo tres objetivos capturados, vinculado scon el robo de tiendas Oxxo.<\/p>\n\n\n\n<p>Durante el mes pasado se registraron 470 detenciones, el 88% por falta administrativa y el resto por delitos.<\/p>\n\n\n\n<p>Sin embargo, las detenciones relacionadas con personas agresivas, estado de ebriedad, merodear, posesi\u00f3n de narc\u00f3ticos, robos y personas intoxicadas, se desplomaron.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuestionada sobre la baja en las detenciones que hubo en noviembre por parte de la Polic\u00eda Municipal de Irapuato, la secretaria de Seguridad, Consuelo Cruz Galindo afirm\u00f3 que las aprehensiones no son parte de la estrategia, sino resultados. La funcionaria expuso que la misma din\u00e1mica de trabajo los obliga a atender otros hechos, como todos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-irapuato"],"_links":{"self":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/10672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/comments?post=10672"}],"version-history":[{"count":1,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/10672\/revisions"}],"predecessor-version":[{"id":10673,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/posts\/10672\/revisions\/10673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media\/9636"}],"wp:attachment":[{"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/media?parent=10672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/categories?post=10672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/primerplanoirapuato.com\/index.php\/wp-json\/wp\/v2\/tags?post=10672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}